{"id":6868,"date":"2023-03-23T09:05:11","date_gmt":"2023-03-23T07:05:11","guid":{"rendered":"https:\/\/ruggerocioffi.it\/?p=6868"},"modified":"2023-03-23T09:05:11","modified_gmt":"2023-03-23T07:05:11","slug":"15-16-giugno-2023-le-meraviglie-della-serenissima","status":"publish","type":"post","link":"https:\/\/ruggerocioffi.it\/en\/15-16-giugno-2023-le-meraviglie-della-serenissima\/","title":{"rendered":"15 &#8211; 16 giugno 2023. LE MERAVIGLIE DELLA SERENISSIMA"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Gioved\u00ec 15 \u2013 Venerd\u00ec 16 giugno 2023 &#8211; Venezia.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un nuovo itinerario Veneziano, questa volta con una maggiore attenzione su alcuni capolavori dell&#8217;architettura e della pittura del XVI e XVII secolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una occasione unica per visitare in modo approfondito le bellissime chiese dei Frari (la pi\u00f9 ricca di opere d&#8217;arte dopo la Basilica di San Marco), di San Rocco con la annessa Scuola (con il celebre ciclo pittorico del Tintoretto e con 60 dipinti ancora conservati nella loro sede originaria), della Piet\u00e0 (dove suon\u00f2 e insegn\u00f2 Antonio Vivaldi).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La possibilit\u00e0 di godere di una visita approfondita delle meraviglie della Galleria dell&#8217;Accademia che ospita la pi\u00f9 ricca collezione di dipinti veneziani e veneti, con artisti che hanno influenzato la storia dell&#8217;arte occidentale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per l&#8217;occasione \u00e8 stato prenotato un prestigioso hotel nei pressi della stazione di Santa Lucia in modo da offrire il massimo comfort e ridurre gli spostamenti di arrivo e partenza.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/424010401190506_Venezia-913722652-1024x683.jpg\" alt=\"\" class=\"wp-image-6869\" srcset=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/424010401190506_Venezia-913722652-1024x683.jpg 1024w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/424010401190506_Venezia-913722652-300x200.jpg 300w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/424010401190506_Venezia-913722652-768x512.jpg 768w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/424010401190506_Venezia-913722652-1536x1024.jpg 1536w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/424010401190506_Venezia-913722652-2048x1365.jpg 2048w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/424010401190506_Venezia-913722652-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Piazza San Marco <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ecco il programma<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gioved\u00ec 15 giugno:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>In tarda mattinata ritrovo dei partecipanti a Venezia, presso la hall del Best Western Premier Collection Continental (molto vicino alla Stazione). Pranzo libero.<\/li>\n\n\n\n<li>Alle 14.00 inizio visite guidate alla Chiesa dei Frari, alla Chiesa e alla Scuola Grande di San Rocco e alla Chiesa della Piet\u00e0 (percorso interamente a piedi con durata totale delle visite di 3 ore).<\/li>\n\n\n\n<li>Segue rientro a piedi in hotel.<\/li>\n\n\n\n<li>Cena libera e pernottamento. <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Venerd\u00ec 16 giugno:  <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dalle 7.30 prima colazione in hotel.<\/li>\n\n\n\n<li>Alle 9.00 passeggiata a piedi e visita della Chiesa dei Gesuati.<\/li>\n\n\n\n<li>Alle 10.30 visita guidata del Museo delle Gallerie dell&#8217;Accademia (durata del percorso interno: due ore).<\/li>\n\n\n\n<li>Alle 12.30 fine dei servizi.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"523\" src=\"http:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/Veronese-convito-in-casa-Levi-1024x523-1.jpg\" alt=\"\" class=\"wp-image-6870\" srcset=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/Veronese-convito-in-casa-Levi-1024x523-1.jpg 1024w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/Veronese-convito-in-casa-Levi-1024x523-1-300x153.jpg 300w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/Veronese-convito-in-casa-Levi-1024x523-1-768x392.jpg 768w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/Veronese-convito-in-casa-Levi-1024x523-1-600x306.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Veronese, il Convito in casa di Levi &#8211; Gallerie dell&#8217;Accademia<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quote di partecipazione:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Con un minimo di 21 partecipanti: euro 330,00<\/li>\n\n\n\n<li>Supplemento camera singola: euro 125,00 <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La quota comprende:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sistemazione presso Best Western Premier Collection CHC Continental in camera doppia con servizi privati con trattamento di BB (tassa di soggiorno esclusa da pagare in loco)<\/li>\n\n\n\n<li>Due guide locali per visite in loco<\/li>\n\n\n\n<li>Prenotazione ed ingresso a tutti i siti museali elencati nel programma (Chiesa dei Frari, Chiesa e Scuola di San Rocco, Chiesa della Piet\u00e0, Chiesa dei Gesuati, Gallerie dell&#8217;Accademia)<\/li>\n\n\n\n<li>Docente e accompagnatore al seguito<\/li>\n\n\n\n<li>Noleggio radioguide con auricolari stereo<\/li>\n\n\n\n<li>Assicurazione medico\/bagaglio e annullamento viaggio + protezione Covid 19<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/21739152305_3404abecfd_k-1024x683-1.jpg\" alt=\"\" class=\"wp-image-6871\" srcset=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/21739152305_3404abecfd_k-1024x683-1.jpg 1024w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/21739152305_3404abecfd_k-1024x683-1-300x200.jpg 300w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/21739152305_3404abecfd_k-1024x683-1-768x512.jpg 768w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/03\/21739152305_3404abecfd_k-1024x683-1-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Scuola Grande di San Rocco<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Treno alta velocit\u00e0 (opzionale): <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>15\/06 Milano Centrale \u2013 Venezia S. Lucia:&nbsp;partenza alle 09.45; arrivo alle 12.12<\/li>\n\n\n\n<li>16\/06 Venezia S. Lucia \u2013 Milano Centrale: partenza&nbsp;alle&nbsp;15.48; arrivo alle 18.15<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quota tariffa comitiva applicabile con almeno 10 adesioni: euro 85,00 per persona<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Informazioni e Prenotazioni <\/strong>al n. 335 7477553 o all\u2019indirizzo mail: <a href=\"mailto:ruggero.cioffi@gmail.com\">ruggero.cioffi@gmail.com<\/a><br>In seguito alla prenotazione, sar\u00e0 richiesta la compilazione del form on-line. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Iscrizioni entro e non oltre il 04\/04\/2023<\/strong>.<br>Successivamente alla prenotazione sar\u00e0 richiesto il pagamento di una caparra pari a 100 euro tramite bonifico all\u2019Agenzia Legnone Tours. Saldo entro il 15 maggio 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N.B: Dal momento in cui si aderisce a questa proposta, il rapporto commerciale sar\u00e0 gestito esclusivamente dall&#8217;Agenzia Legnone Tours. Vi prego quindi di consultare Legnone Tours per eventuali dubbi o richieste di chiarimenti per quanto riguarda: casi di rinuncia per problemi familiari, casi di malattia, ecc. Il programma pu\u00f2 subire variazioni dovute al maltempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Direzione tecnica e operativa del tour:<\/strong><br>LEGNONE TOURS SRL<br>Piazza San Francesco, 7 \u2013 21047 Saronno (VA); tel. 0296709950; mail: infosaronno@legnonetours.com Licenza: scia n. 64850 del 29\/12\/2014 (prec. licenza 24709 del 18\/11\/88)<br>Fondo di garanzia: FONDO VACANZE FELICI S.C.A.R.L.<br>Polizza RC: Unipol Sai Assicurazioni Spa n. 165556407<\/p>\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\">\n\n\n\n\n\n\n\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Un nuovo itinerario tra i tesori pittorici e architettonici di Venezia<\/p>","protected":false},"author":1,"featured_media":6872,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[93,94],"tags":[],"class_list":["post-6868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calendario","category-viaggi"],"_links":{"self":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts\/6868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/comments?post=6868"}],"version-history":[{"count":0,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts\/6868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/media\/6872"}],"wp:attachment":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/media?parent=6868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/categories?post=6868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/tags?post=6868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}