{"id":7517,"date":"2023-07-15T21:22:09","date_gmt":"2023-07-15T19:22:09","guid":{"rendered":"https:\/\/ruggerocioffi.it\/?p=7517"},"modified":"2023-07-15T21:22:09","modified_gmt":"2023-07-15T19:22:09","slug":"17-19-novembre-2023-storie-da-uneruzione","status":"publish","type":"post","link":"https:\/\/ruggerocioffi.it\/en\/17-19-novembre-2023-storie-da-uneruzione\/","title":{"rendered":"17 &#8211; 19 novembre 2023. STORIE DA UN&#8217;ERUZIONE (REPLICA)"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Venerd\u00ec 17 \u2013 Domenica 19 novembre 2023 &#8211; Pompei, Ercolano, Portici.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visitare Ercolano e Pompei ancora oggi suscita profonda emozione. Non solo per l&#8217;incredibile stato di conservazione di queste antiche citt\u00e0, ma anche perch\u00e9 percorrendo le strade di questi celebri scavi archeologici abbiamo tutti la sensazione di ritrovare le tracce vive e tangibili del nostro passato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un itinerario appositamente studiato per narrare delle storie di vita vissuta, le vicende degli aristocratici e degli umili che abitarono questo florido territorio, riscoperto in epoca borbonica e &#8211; da trecento anni a questa parte &#8211; fiore all&#8217;occhiello del nostro patrimonio storico e artistico. L&#8217;occasione unica e irripetibile di visitare una mostra prestigiosa presso la Reggia di Portici: &#8220;Materia, il legno che non bruci\u00f2 ad Ercolano&#8221;, che per la prima volta presenta al pubblico&nbsp;<strong>oltre 120 oggetti in legno<\/strong>&nbsp;che il Vesuvio non ha distrutto ma carbonizzato, preservandoli cos\u00ec fino ai nostri giorni.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"800\" src=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/pompeii-tour-2_1610728735.jpg.webp\" alt=\"\" class=\"wp-image-6450\" srcset=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/pompeii-tour-2_1610728735.jpg.webp 1024w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/pompeii-tour-2_1610728735.jpg-300x234.webp 300w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/pompeii-tour-2_1610728735.jpg-768x600.webp 768w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/pompeii-tour-2_1610728735.jpg-600x469.webp 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Il Foro di Pompei <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ecco il programma<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Venerd\u00ec 17 novembre:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alle 12.00 ritrovo alla Stazione di Napoli\/Afragola e trasferimento bus navetta privata ad Ercolano. Segue pausa pranzo libero ad Ercolano.<\/li>\n\n\n\n<li>Alle 14.00 visita guidata al Parco Archeologico di Ercolano (durata visita : 2,5 ore)<\/li>\n\n\n\n<li>Alle 17.00 partenza per Napoli, check in hotel (Terminus), cena libera e pernottamento.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sabato 18 novembre:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dalle 7.30 prima colazione in hotel.<\/li>\n\n\n\n<li>Alle 9.00 partenza per Pompei in bus navetta privata.<\/li>\n\n\n\n<li>Dalle 9.45 visita guidata al Parco Archeologico di Pompei (la visita sar\u00e0 divisa in itinerario della mattina, pausa pranzo libero all&#8217;interno del Parco Archeologico, e successivo itinerario del pomeriggio). <\/li>\n\n\n\n<li>Alle 17.30 partenza per rientro a Napoli, cena libera e pernottamento.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Domenica 19 novembre:  <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dalle 7.30 prima colazione in hotel<\/li>\n\n\n\n<li>Alle 9.00 partenza per Portici in bus navetta privata.<\/li>\n\n\n\n<li>Alle 10.00 visita guidata alla mostra &#8220;Materia, il legno che non bruci\u00f2 ad Ercolano&#8221;<\/li>\n\n\n\n<li>Alle 11.30 partenza per rientro a Napoli e fine dei servizi.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"583\" src=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/Getty-Villa-cosa-vedere-1024x583.jpeg\" alt=\"\" class=\"wp-image-6451\" srcset=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/Getty-Villa-cosa-vedere-1024x583.jpeg 1024w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/Getty-Villa-cosa-vedere-300x171.jpeg 300w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/Getty-Villa-cosa-vedere-768x437.jpeg 768w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/Getty-Villa-cosa-vedere-600x341.jpeg 600w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/Getty-Villa-cosa-vedere.jpeg 1320w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ricostruzione della Villa dei Papiri<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quote di partecipazione:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Con un minimo di 20 partecipanti: euro 500,00.<\/li>\n\n\n\n<li>Con un minimo di 25 partecipanti: euro 475,00<\/li>\n\n\n\n<li>Supplemento camera singola: euro 120,00 <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La quota comprende:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sistemazione presso Hotel Terminus 4 stelle di Napoli in camera doppia con servizi privati<\/li>\n\n\n\n<li>Trattamento di pernottamento e prima colazione<\/li>\n\n\n\n<li>Guida locale ed esperta archeologa a disposizione del gruppo<\/li>\n\n\n\n<li>Servizio navetta privato per i trasferimenti a Ercolano, Pompei, Portici<\/li>\n\n\n\n<li>Prenotazione ed ingresso a tutti i siti elencati nel programma<\/li>\n\n\n\n<li>Docente e accompagnatore al seguito<\/li>\n\n\n\n<li>Noleggio radioguide con auricolari stereo<\/li>\n\n\n\n<li>Assicurazione medico, bagaglio e annullamento inclusa protezione Covid 19<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"630\" height=\"420\" src=\"http:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/62-Inv.77771-Applique-di-letto-con-ninfa-01-\u00a9luigispina-630x420-1.jpg\" alt=\"\" class=\"wp-image-6452\" style=\"width:840px;height:560px\" srcset=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/62-Inv.77771-Applique-di-letto-con-ninfa-01-\u00a9luigispina-630x420-1.jpg 630w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/62-Inv.77771-Applique-di-letto-con-ninfa-01-\u00a9luigispina-630x420-1-300x200.jpg 300w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2023\/01\/62-Inv.77771-Applique-di-letto-con-ninfa-01-\u00a9luigispina-630x420-1-600x400.jpg 600w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><figcaption class=\"wp-element-caption\">Applique di bronzo con Ninfa (dalla mostra Materia)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Treno alta velocit\u00e0 (opzionale): <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>17\/11 Milano Centrale \u2013 Napoli Afragola:&nbsp;partenza alle 07.30; arrivo alle 11.48<\/li>\n\n\n\n<li>19\/11 Napoli Centrale \u2013 Milano Centrale: partenza&nbsp;alle&nbsp;14.30; arrivo alle 19.00<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quota tariffa comitiva applicabile con almeno 10 adesioni: euro 145,00 per persona<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Informazioni e Prenotazioni <\/strong>al n. 335 7477553 o all\u2019indirizzo mail: <a href=\"mailto:ruggero.cioffi@gmail.com\">ruggero.cioffi@gmail.com<\/a><br>In seguito alla prenotazione, sar\u00e0 richiesta la compilazione del form on-line. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Iscrizioni entro e non oltre il 31\/08\/2023<\/strong>.<br>Successivamente alla prenotazione sar\u00e0 richiesto il pagamento tramite bonifico all\u2019Agenzia Legnone Tours della caparra confirmatoria pari ad euro 140. Saldo entro un mese dalla partenza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N.B: Dal momento in cui si aderisce a questa proposta, il rapporto commerciale sar\u00e0 gestito esclusivamente dall&#8217;Agenzia Legnone Tours. Vi prego quindi di consultare Legnone Tours per eventuali dubbi o richieste di chiarimenti per quanto riguarda: casi di rinuncia per problemi familiari, casi di malattia, ecc. Il programma pu\u00f2 subire variazioni dovute al maltempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Direzione tecnica e operativa del tour:<\/strong><br>LEGNONE TOURS SRL<br>Piazza San Francesco, 7 \u2013 21047 Saronno (VA); tel. 0296709950; mail: infosaronno@legnonetours.com Licenza: scia n. 64850 del 29\/12\/2014 (prec. licenza 24709 del 18\/11\/88)<br>Fondo di garanzia: FONDO VACANZE FELICI S.C.A.R.L.<br>Polizza RC: Unipol Sai Assicurazioni Spa n. 165556407<\/p>\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\">\n\n\n\n\n\n\n\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Ripercorri con noi la straordinaria scoperta di Pompei ed Ercolano con le &#8220;Storie da un&#8217;eruzione&#8221;<\/p>","protected":false},"author":1,"featured_media":6458,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[93,94],"tags":[],"class_list":["post-7517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calendario","category-viaggi"],"_links":{"self":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts\/7517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/comments?post=7517"}],"version-history":[{"count":0,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts\/7517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/media\/6458"}],"wp:attachment":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/media?parent=7517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/categories?post=7517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/tags?post=7517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}