{"id":8392,"date":"2019-10-21T15:50:03","date_gmt":"2019-10-21T15:50:03","guid":{"rendered":"https:\/\/ruggerocioffi.it\/?p=1934"},"modified":"2019-10-21T15:50:03","modified_gmt":"2019-10-21T15:50:03","slug":"festa-della-biblioteca-paolo-volonte-di-cormano","status":"publish","type":"post","link":"https:\/\/ruggerocioffi.it\/en\/festa-della-biblioteca-paolo-volonte-di-cormano\/","title":{"rendered":"Festa della Biblioteca &#8220;Paolo Volont\u00e8&#8221; di Cormano"},"content":{"rendered":"<p><img decoding=\"async\" width=\"300\" height=\"166\" class=\"size-medium wp-image-1936 alignleft\" src=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2019\/10\/PHOTO-2019-10-21-16-37-47-300x166.jpg\" alt=\"\" srcset=\"https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2019\/10\/PHOTO-2019-10-21-16-37-47-300x166.jpg 300w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2019\/10\/PHOTO-2019-10-21-16-37-47-600x333.jpg 600w, https:\/\/ruggerocioffi.it\/wp-content\/uploads\/2019\/10\/PHOTO-2019-10-21-16-37-47.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Tanta emozione e soddisfazione sabato 19 a Cormano.<br \/>\nUna biblioteca stracolma di persone che ho trovato molto interessate e partecipi alla mia conferenza su Leonardo.<\/p>\n<p>E&#8217; chiaro che questo \u00e8 il risultato di un eccellente lavoro di squadra svolto dai miei cari colleghi Edward Danieli e Valentina Villa che hanno promosso l&#8217;evento nel migliore dei modi, Un sincero grazie anche all&#8217;Assessore Roberta Zanzani che mi ha accolto tanto affabilmente assieme al Sindaco e alla dott.ssa Annamaria Arcidiacono, dirigente del Settore Eventi Culturali.<br \/>\nQui sotto, il commento dell&#8217;Assessore Roberta Zanzani.<\/p>\n<p><span style=\"font-size: inherit;\">&#8220;Alla Festa della Biblioteca &#8220;Paolo Volont\u00e8&#8221; di Cormano, sabato 19 ottobre, il Prof. Ruggero Cioffi, docente e appassionato divulgatore culturale, ha tenuto una coinvolgente conferenza: &#8220;Leonardo il genio assoluto&#8221;. Il prof. Cioffi ci ha accompagnato alla ricerca dell&#8217;artista, dell&#8217;uomo curioso e dello scienziato Leonardo Da Vinci.&#8221;<\/span><\/p>\n<p><em>&#8211; Roberta Zanzani, Assessore a Politiche sociali e Servizi per la salute, Politiche abitative e per l&#8217;integrazione, Pari opportunit\u00e0 e Cultura del Comune di Cormano.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Tanta emozione e soddisfazione sabato 19 a Cormano.<br \/>\nUna biblioteca stracolma di persone che ho trovato molto interessate e partecipi alla mia conferenza su Leonardo. E&#8217; chiaro che questo \u00e8 il risultato di un eccellente lavoro di squadra svolto dai miei cari colleghi Edward Danieli e Valentina Villa che hanno promosso l&#8217;evento nel migliore dei modi, Un sincero grazie anche all&#8217;Assessore Roberta Zanzani che mi ha accolto tanto affabilmente assieme al Sindaco e alla dirigente del Settore Eventi Culturali.<\/p>","protected":false},"author":1,"featured_media":1935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[95,96],"tags":[],"class_list":["post-8392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-didattica","category-portfolio"],"_links":{"self":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts\/8392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/comments?post=8392"}],"version-history":[{"count":0,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/posts\/8392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/media\/1935"}],"wp:attachment":[{"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/media?parent=8392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/categories?post=8392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ruggerocioffi.it\/en\/wp-json\/wp\/v2\/tags?post=8392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}